{"id":120071,"date":"2025-11-20T14:16:09","date_gmt":"2025-11-20T13:16:09","guid":{"rendered":"https:\/\/www.tcbo.it\/eventi\/opera-2026-naples-millionaires\/"},"modified":"2026-05-05T11:28:21","modified_gmt":"2026-05-05T10:28:21","slug":"opera-2026-naples-millionaires","status":"publish","type":"portfolio","link":"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/","title":{"rendered":"Opera 2026 | Naples Millionaires"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;6&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; content_parallax=&#8221;0&#8243; uncode_shortcode_id=&#8221;130512&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;1&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;2\/3&#8243; uncode_shortcode_id=&#8221;899490&#8243;][vc_column_text text_lead=&#8221;yes&#8221; uncode_shortcode_id=&#8221;183245&#8243;]<\/p>\n<p style=\"text-align: left;\"><span style=\"color: #a61620;\"><em>OPERA 2026<\/em><\/span><\/p>\n<p>[\/vc_column_text][vc_custom_heading text_size=&#8221;fontsize-338686&#8243; text_space=&#8221;fontspace-210350&#8243; uncode_shortcode_id=&#8221;135228&#8243;]NAPLES MILLIONAIRE[\/vc_custom_heading][vc_column_text uncode_shortcode_id=&#8221;648689&#8243;]<\/p>\n<h4 style=\"text-align: left;\"><span class=\"font-850707\" style=\"color: #333333;\">Nino Rota<\/span><\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; border_color=&#8221;color-uydo&#8221; border_style=&#8221;solid&#8221; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; uncode_shortcode_id=&#8221;110032&#8243; css=&#8221;.vc_custom_1761666294901{border-left-width: 1px !important;padding-left: 10px !important;}&#8221; border_color_type=&#8221;uncode-palette&#8221;][vc_custom_heading text_size=&#8221;h3&#8243; text_space=&#8221;fontspace-210350&#8243; uncode_shortcode_id=&#8221;198477&#8243;]<span class=\"font-850707\" style=\"color: #333333;\">12 | 13* | 14 | 16* | 17 giugno<\/span><\/p>\n<p><span style=\"color: #808080;\">Comunale Nouveau<\/span>[\/vc_custom_heading][vc_button radius=&#8221;btn-round&#8221; shadow=&#8221;yes&#8221; border_width=&#8221;0&#8243; button_color_type=&#8221;uncode-solid&#8221; uncode_shortcode_id=&#8221;711654&#8243; button_color_solid=&#8221;#3b7271&#8243; link=&#8221;url:https%3A%2F%2Ftcbo.vivaticket.it%2Fit%2Fevent%2Fnapoli-milionaria%2F290795|&#8221;]acquista il tuo biglietto[\/vc_button][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;6&#8243; top_padding=&#8221;1&#8243; bottom_padding=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; content_parallax=&#8221;0&#8243; uncode_shortcode_id=&#8221;906144&#8243;][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;2\/3&#8243; uncode_shortcode_id=&#8221;173916&#8243;][vc_column_text uncode_shortcode_id=&#8221;405927&#8243;]Opera lirica in tre atti<br \/>\nLibrettista <strong>Eduardo De Filippo<br \/>\n<\/strong>Tratto dall&#8217;omonima commedia[\/vc_column_text][vc_accordion sign=&#8221;plus&#8221; gutter_simple=&#8221;0&#8243; active_tab=&#8221;0&#8243; uncode_shortcode_id=&#8221;200966&#8243;][vc_accordion_tab icon=&#8221;fa fa-file-text&#8221; gutter_size=&#8221;2&#8243; column_padding=&#8221;2&#8243; title=&#8221;CLICK TO READ MORE&#8221; tab_id=&#8221;cb101898-0fee-54&#8243;][vc_column_text uncode_shortcode_id=&#8221;170750&#8243; css=&#8221;.vc_custom_1765892830277{padding-right: 20px !important;padding-left: 20px !important;}&#8221;]Una finta veglia funebre inscenata per ingannare la legge. Potrebbe essere una scena da <i>Gianni Schicchi<\/i>, si ride, si ride anche parecchio. Poi, all&#8217;improvviso, le bombe: tutto cambia e un comprimario, uno di quei personaggi che avevamo notato appena a dar colore a una scena, torna alla ribalta annunciando che la moglie \u00e8 morta sotto le macerie. Il falso e il vero. Cos\u00ec si chiude il primo atto di <i>Napoli milionaria<\/i>: l&#8217;opera buffa e la tragedia, l&#8217;arte di arrangiarsi che diventa farsa giocosa e la storia che irrompe violenta e spietata.<span class=\"Apple-converted-space\">\u00a0 <\/span>Un mondo si racchiude in questa seconda collaborazione (1977) fra Eduardo De Filippo e Nino Rota (la prima era stata la fiaba<i> Uno scoiattolo in gamba<\/i>, del 1959) che del compositore sar\u00e0 anche l&#8217;ultima opera.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La famiglia Jovine e il microcosmo del basso napoletano sono in lotta per la sopravvivenza fra gli ultimi fuochi del fascismo, la seconda guerra mondiale, le euforie e le contraddizioni del dopoguerra. La musica di Rota calza come un guanto alle sfaccettature dell&#8217;amarissima commedia, padroneggiando disinvolto linguaggi, registri, umori differenti. De Filippo riscrive il proprio testo mostrandosi librettista a tutti gli effetti e <i>Napoli milionaria<\/i>\u00a0\u00e8 un vero capolavoro del melodramma del XX secolo, un&#8217;opera scritta con la sapienza propria dei veri grandi, con una profondit\u00e0 di pensiero e di linguaggio posta al servizio del teatro, di un racconto senza speranza, durissimo, eppure sfaccettato anche fra sorrisi, ironie e dolcezze.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_separator sep_color=&#8221;&#8221; icon=&#8221;fa fa-music&#8221; icon_position=&#8221;left&#8221; uncode_shortcode_id=&#8221;922886&#8243;][vc_row_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;832743&#8243;][vc_column_text uncode_shortcode_id=&#8221;144906&#8243;]<\/p>\n<h5 style=\"text-align: left;\"><span style=\"color: #808080;\">Maestro concertatore e Direttore<br \/>\n<\/span><strong>James Feddeck<\/strong><\/h5>\n<p>[\/vc_column_text][vc_single_image media=&#8221;100941&#8243; media_width_percent=&#8221;30&#8243; shape=&#8221;img-round&#8221; uncode_shortcode_id=&#8221;203164&#8243; media_link=&#8221;url:https%3A%2F%2Fwww.jamesfeddeck.com&#8221;][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;142377&#8243;][vc_column_text uncode_shortcode_id=&#8221;109278&#8243;]<\/p>\n<h5 style=\"text-align: left;\"><span style=\"color: #808080;\">Regia<br \/>\n<\/span><strong>Marcelo Lombardero<\/strong><\/h5>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text uncode_shortcode_id=&#8221;214615&#8243;]Nuovo allestimento del Teatro Comunale di Bologna<br \/>\n<span style=\"color: #333333;\"><strong>Orchestra, Coro e Tecnici del Teatro Comunale di Bologna<\/strong><\/span><\/p>\n<h5><span style=\"color: #333333;\"><strong><span style=\"color: #808080;\">Maestro del Coro<\/span> <b>Giovanni Farina<\/b><\/strong><\/span><\/h5>\n<p>[\/vc_column_text][vc_row_inner limit_content=&#8221;&#8221;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;735210&#8243;][vc_separator sep_color=&#8221;&#8221; icon=&#8221;fa fa-user&#8221; icon_position=&#8221;left&#8221; uncode_shortcode_id=&#8221;222722&#8243;][vc_column_text uncode_shortcode_id=&#8221;760608&#8243;]<\/p>\n<h4><span style=\"color: #333333;\"><span style=\"caret-color: #333333;\">Personaggi e interpreti<\/span><\/span><\/h4>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;344279&#8243;]<\/p>\n<p style=\"text-align: left;\">ERRICO &#8220;SETTEBELLIZZE&#8221;<span style=\"color: #333333;\"><br \/>\n<strong>Matteo Falcier\/Kazuki Yoshida*<\/strong><br \/>\n<\/span><\/p>\n<p>PEPPE O&#8217;CRICCO<br \/>\n<span style=\"color: #333333;\"><strong>Giulio Iermini<\/strong><\/span><\/p>\n<p>FEDERICO | PETER<br \/>\n<strong><span style=\"color: #333333;\">Michele Patti<\/span><\/strong><\/p>\n<p>RICCARDO SPASIANO<br \/>\n<strong><span style=\"color: #333333;\">Luca Park<\/span><\/strong><\/p>\n<p>O MIEZZO PREVETE<br \/>\n<span style=\"color: #333333;\"><strong>Michele Giaquinto<\/strong><\/span><\/p>\n<p>PASCALINO &#8220;O PITTORE&#8221;<br \/>\n<span style=\"color: #333333;\"><strong>Xin Zhang<\/strong><\/span><\/p>\n<p>GENNARO JOVINE<br \/>\n<span style=\"color: #333333;\"><strong>Paolo Bordogna\/Bruno Taddia*<\/strong><\/span><\/p>\n<p>AMALIA<br \/>\n<span style=\"color: #333333;\"><strong>Carmen Giannattasio\/Laura Stella*<\/strong><\/span><\/p>\n<p>MARIA ROSARIA<br \/>\n<span style=\"color: #333333;\"><strong>Mariam Battistelli\/Claudia Ceraulo*<\/strong><\/span><\/p>\n<p>AMEDEO<br \/>\n<span style=\"color: #333333;\"><strong>Marco Miglietta\/Raffaele Feo*<\/strong><\/span><\/p>\n<p>IL BRIGADIERE CIAPPA<br \/>\n<span style=\"color: #333333;\"><strong>Yuri Guerra<\/strong><\/span><\/p>\n<p>ADELAIDE SCHIANO<br \/>\n<span style=\"color: #333333;\"><strong>Benedetta Mazzetto<\/strong><\/span><\/p>\n<p>ASSUNTA<br \/>\n<span style=\"color: #333333;\"><strong>Eleonora Filipponi<\/strong><\/span>[\/vc_column_text][\/vc_column_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/2&#8243; uncode_shortcode_id=&#8221;161213&#8243;][vc_separator sep_color=&#8221;&#8221; icon=&#8221;fa fa-magic&#8221; icon_position=&#8221;left&#8221; uncode_shortcode_id=&#8221;167928&#8243;][vc_column_text uncode_shortcode_id=&#8221;823796&#8243;]<\/p>\n<h4><span style=\"color: #333333;\"><span style=\"caret-color: #333333;\">Team creativo<\/span><\/span><\/h4>\n<p>[\/vc_column_text][vc_column_text uncode_shortcode_id=&#8221;731235&#8243;]<\/p>\n<p style=\"text-align: left;\">SCENE<span style=\"color: #333333;\"><br \/>\n<strong>Diego Siliano<\/strong><br \/>\n<\/span><\/p>\n<p>COSTUMI<br \/>\n<span style=\"color: #333333;\"><strong>Luciana Gutman<\/strong><\/span><\/p>\n<p>LUCI<br \/>\n<span style=\"color: #333333;\"><strong>Marcelo Lombardero<\/strong><\/span>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_separator sep_color=&#8221;&#8221; icon=&#8221;fa fa-music&#8221; icon_position=&#8221;left&#8221; uncode_shortcode_id=&#8221;127761&#8243;][vc_column_text uncode_shortcode_id=&#8221;191217&#8243;]<\/p>\n<h4><strong>Orchestra e Coro del Teatro Comunale di Bologna\u00a0<\/strong><\/h4>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_accordion sign=&#8221;plus&#8221; gutter_simple=&#8221;0&#8243; active_tab=&#8221;0&#8243; uncode_shortcode_id=&#8221;203483&#8243;][vc_accordion_tab icon=&#8221;fa fa-clock&#8221; gutter_size=&#8221;3&#8243; column_padding=&#8221;2&#8243; title=&#8221;DATES AND TIMES&#8221; tab_id=&#8221;085e0cd9-b636-516346481760651656776120017173080967273017308100880911730810355360173081116598617308129737681730814164728&#8243;][vc_column_text uncode_shortcode_id=&#8221;487042&#8243;]<strong>12 giu | H 20:00 <\/strong>&#8211; PRIME<br \/>\n<strong>13 giu | 18:00 <\/strong>&#8211; POMERIGGIO 1<br \/>\n<strong>14 giu | H 16:00 <\/strong>&#8211; DOMENICA<br \/>\n<strong>16 giu | 18:00 <\/strong>&#8211; POMERIGGIO 2<br \/>\n<strong>17 giu | H 20:00 <\/strong>&#8211; SERA[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab icon=&#8221;fa fa-hourglass&#8221; gutter_size=&#8221;2&#8243; column_padding=&#8221;2&#8243; title=&#8221;DURATION&#8221; tab_id=&#8221;07a9ee9a-4419-1173080967273017308100880911730810355360173081116598617308129737681730814164728&#8243;][vc_column_text uncode_shortcode_id=&#8221;182812&#8243;]Atto 1 e 2: 80min.<br \/>\nIntervallo: 25min.<br \/>\nAtto 3: 45min.<\/p>\n<p><strong>2h e 30 min.<\/strong>[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab icon=&#8221;fa fa-graduation-hat&#8221; gutter_size=&#8221;2&#8243; column_padding=&#8221;2&#8243; title=&#8221;STUDENTS&#8221; tab_id=&#8221;193081e2-097a-0&#8243;][vc_column_text uncode_shortcode_id=&#8221;556817&#8243;]<strong>Biglietti a 10\u20ac per tutti gli studenti iscritti all&#8217;Universit\u00e0 di Bologna, all&#8217;Accademia di Belle Arti di Bologna e al Conservatorio di Musica G.B. Martini per gli spettacoli della Stagione Opera 2026.<br \/>\n<\/strong>In vendita solo negli orari di prevendita della Biglietteria (dal marted\u00ec al venerd\u00ec dalle 12 alle 18 e il sabato dalle 11 alle 15), da un mese prima della Prima, presentando badge universitario e autocertificazione di iscrizione all&#8217;anno in corso.[\/vc_column_text][\/vc_accordion_tab][vc_accordion_tab icon=&#8221;fa fa-microphone2&#8243; gutter_size=&#8221;2&#8243; column_padding=&#8221;2&#8243; title=&#8221;INTRODUCTION TO THE WORK&#8221; tab_id=&#8221;cb101898-0fee-5&#8243;][vc_column_text uncode_shortcode_id=&#8221;159426&#8243;]<span style=\"color: #333333;\"><strong>45 min. <\/strong><\/span>before the start of the performance, the audience is invited to an in-depth discussion of the work by <span style=\"color: #333333;\"><strong>Luca Baccolini<\/strong><\/span>, which will be held in the Foyer of the Comunale Nouveau.[\/vc_column_text][vc_single_image media=&#8221;102060&#8243; media_width_percent=&#8221;20&#8243; uncode_shortcode_id=&#8221;103245&#8243;][vc_column_text text_lead=&#8221;small&#8221; uncode_shortcode_id=&#8221;116031&#8243;]<strong>Luca Baccolini<\/strong><br \/>\nGiornalista, divulgatore musicale e scrittore, collabora con la redazione bolognese di <em>Repubblica<\/em> ed \u00e8 nella redazione del mensile <em>Classic Voice<\/em>. Per Newton Compton ha pubblicato dieci libri sulla storia di Bologna. \u00c8 autore di soggetti teatrali e collabora in veste di saggista e divulgatore con le pi\u00f9 importanti istituzioni lirico sinfoniche italiane.[\/vc_column_text][\/vc_accordion_tab][\/vc_accordion][vc_button size=&#8221;btn-sm&#8221; radius=&#8221;btn-round&#8221; shadow=&#8221;yes&#8221; border_width=&#8221;0&#8243; button_color_type=&#8221;uncode-solid&#8221; uncode_shortcode_id=&#8221;171868&#8243; link=&#8221;url:https%3A%2F%2Fwww.tcbo.it%2Fstagione-opera-2026%2F|title:Stagione%20Opera%202025|target:_blank|&#8221; button_color_solid=&#8221;#5cbdb5&#8243;]OPERA CALENDAR 2026[\/vc_button][vc_row_inner][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;2&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; uncode_shortcode_id=&#8221;136473&#8243;][vc_column_text uncode_shortcode_id=&#8221;127201&#8243;]Presenting Partner[\/vc_column_text][vc_single_image media=&#8221;97331&#8243; media_width_percent=&#8221;55&#8243; uncode_shortcode_id=&#8221;104981&#8243;][\/vc_column_inner][\/vc_row_inner][vc_column_text uncode_shortcode_id=&#8221;208666&#8243;]Segui l&#8217;opera con[\/vc_column_text][vc_single_image media=&#8221;60781&#8243; media_width_percent=&#8221;25&#8243; uncode_shortcode_id=&#8221;142050&#8243; media_link=&#8221;url:https%3A%2F%2Fwww.lyri.it%2Fit%2F%23surtitles&#8221;][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; override_padding=&#8221;yes&#8221; h_padding=&#8221;0&#8243; top_padding=&#8221;2&#8243; bottom_padding=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; content_parallax=&#8221;0&#8243; uncode_shortcode_id=&#8221;152721&#8243;][vc_column width=&#8221;1\/1&#8243;][vc_separator sep_color=&#8221;color-prif&#8221; uncode_shortcode_id=&#8221;129678&#8243; sep_color_type=&#8221;uncode-palette&#8221;][vc_column_text text_lead=&#8221;small&#8221; uncode_shortcode_id=&#8221;435081&#8243;]<div class=\"eventCalendarFilter\"><span class=\"eventCalendarTerm active\" data-term=\"reset\">All Events<\/span><span class=\"eventCalendarTerm\" data-term=\"opera\">Opera<\/span><span class=\"eventCalendarTerm\" data-term=\"danza\">Dance<\/span><span class=\"eventCalendarTerm\" data-term=\"concerti\">Concerts<\/span><span class=\"eventCalendarTerm\" data-term=\"altri-eventi\">Other Events<\/span><\/div><div class=\"swiper eventCalendarContainer sameHeightWrap\" data-height=\".craqEventCalendarSlide\" data-limt=\"1\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-olympia\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">15<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Olympia<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-olympia\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">17<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Olympia<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 16:00<\/div><a role=\"button\" href=\"https:\/\/tcbo.vivaticket.it\/it\/event\/olympia\/290797\" class=\"custom-link btn border-width-0 btn-round btn-shadow btn-icon-left cursor-init eventCalendarTicketBtn\" target=\"_blank\" rel=\"noopener noreferrer\">BUY YOUR TICKET<\/a><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-olympia\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">19<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Olympia<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-carmen\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">23<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Carmen<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-carmen\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">24<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Carmen<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 16:00<\/div><a role=\"button\" href=\"https:\/\/tcbo.vivaticket.it\/it\/event\/carmen-balletto\/289977\" class=\"custom-link btn border-width-0 btn-round btn-shadow btn-icon-left cursor-init eventCalendarTicketBtn\" target=\"_blank\" rel=\"noopener noreferrer\">BUY YOUR TICKET<\/a><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/8_Foron_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-foron\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">25<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Foron<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-joy-symphony-no-6\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">31<\/div><div class=\"eventCalendarMonth\">May<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Joy &#8211; Symphony No. 6<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 11:00<\/div><a role=\"button\" href=\"https:\/\/tcbo.vivaticket.it\/it\/event\/beethoven-sinfonia-n-6\/289954%20_blank\" class=\"custom-link btn border-width-0 btn-round btn-shadow btn-icon-left cursor-init eventCalendarTicketBtn\" target=\"_blank\" rel=\"noopener noreferrer\">BUY YOUR TICKET<\/a><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">12<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Naples Millionaires<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">13<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Naples Millionaires<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 18:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">14<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Naples Millionaires<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 16:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">16<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Naples Millionaires<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 18:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-naples-millionaires\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">17<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Naples Millionaires<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-cluster\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">24<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Cluster<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-cluster\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">25<\/div><div class=\"eventCalendarMonth\">June<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Cluster<\/h3><div class=\"eventCalendarPlace\">Comunale Nouveau, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-caravaggio\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">8<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Caravaggio<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-caravaggio\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">9<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Caravaggio<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-caravaggio\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">10<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Caravaggio<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 16:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-caravaggio\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">10<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Caravaggio<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/9_Sado_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-sado\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">16<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Sado<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-semele\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">23<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Semele<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-semele\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">25<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Semele<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 16:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/10_Abbado_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-abbado\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">26<\/div><div class=\"eventCalendarMonth\">October<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Abbado<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/11_Chauhan_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-chauhan\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">6<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Chauhan<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-samson-et-dalila\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">13<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Samson et Dalila<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide opera\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/opera-2026-samson-et-dalila\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">15<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Opera<\/div><h3 class=\"eventCalendarTitle\">Opera 2026 | Samson et Dalila<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 16:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/12_Bolton_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-bolton\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">20<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Bolton<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-joy-symphony-no-7\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">22<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Joy &#8211; Symphony No. 7<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 11:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-morricone-night\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">28<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Morricone Night<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide danza\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/dance-2026-morricone-night\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">29<\/div><div class=\"eventCalendarMonth\">November<\/div><div class=\"eventCalendarTerms\">Dance<\/div><h3 class=\"eventCalendarTitle\">Dance 2026 | Morricone Night<\/h3><div class=\"eventCalendarPlace\">Teatro EuropAuditorium, 16:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/13_Angius_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-angius\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">11<\/div><div class=\"eventCalendarMonth\">December<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Angius<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 20:30<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2023\/04\/basic_thumbnail_event_calendar.png&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-joy-symphony-no-8\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">13<\/div><div class=\"eventCalendarMonth\">December<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Joy &#8211; Symphony No. 8<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 11:00<\/div><\/div><\/div><div class=\"swiper-slide craqEventCalendarSlide concerti\"><div class=\"eventCalendarWrap\"><div class=\"absoluteInRelative backgroundCover eventCalendarImg lazyload\" style=\"background-image:inherit\" data-bg-image=\"url(&#039;https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/11\/14_Stenz_1080x1080.jpg&#039;)\"><\/div><a href=\"https:\/\/www.tcbo.it\/en\/eventi\/concerts-2026-symphony-stenz\/\" class=\"absoluteInRelative\"><\/a><div class=\"eventCalendarDay\">31<\/div><div class=\"eventCalendarMonth\">December<\/div><div class=\"eventCalendarTerms\">Concerts<\/div><h3 class=\"eventCalendarTitle\">Concerts 2026 | Symphony &#8211; Stenz<\/h3><div class=\"eventCalendarPlace\">Teatro Manzoni, 16:00<\/div><\/div><\/div><\/div><\/div><div class=\"swiper-buttons-container\"><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div><\/div>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;4\/6&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;149354&#8243;]<\/p>\n<h4><span class=\"font-168876 font-762333 font-202503\" style=\"color: #808080;\">Let&#8217;s talk about Opera | Opera Season 2025<\/span><\/h4>\n<h1><span style=\"color: #993300; font-family: Poppins;\">LET&#8217;S TALK ABOUT &#8220;A MASQUERADE BALL&#8221;<\/span><\/h1>\n<h2><span style=\"color: #993300; font-family: Poppins;\">WITH <span style=\"color: #333333;\">LODO GUENZI<\/span><\/span><\/h2>\n<p>[\/vc_custom_heading][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; limit_content=&#8221;&#8221; uncode_shortcode_id=&#8221;218726&#8243;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_color=&#8221;color-gyho&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; <\/p><\/div>&hellip;","protected":false},"author":18,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"portfolio_category":[81,93,144,496,556],"class_list":["post-120071","portfolio","type-portfolio","status-publish","hentry","portfolio_category-opera","portfolio_category-opera-en","portfolio_category-calendario","portfolio_category-calendario-en","portfolio_category-556"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Opera 2026 | Naples Millionaires - Teatro Comunale di Bologna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Opera 2026 | Naples Millionaires\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column width=&#8221;4\/6&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;149354&#8243;] Let&#8217;s talk about Opera | Opera Season 2025 LET&#8217;S TALK ABOUT &#8220;A MASQUERADE BALL&#8221; WITH LODO GUENZI [\/vc_custom_heading][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; limit_content=&#8221;&#8221; uncode_shortcode_id=&#8221;218726&#8243;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_color=&#8221;color-gyho&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Teatro Comunale di Bologna\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TeatroComunaleBologna\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T10:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/12\/yoast_Napoli-milionaria-1024x576.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ComunaleBologna\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/opera-2026-napoli-milionaria\\\/\",\"url\":\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/opera-2026-napoli-milionaria\\\/\",\"name\":\"Opera 2026 | Naples Millionaires - Teatro Comunale di Bologna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#website\"},\"datePublished\":\"2025-11-20T13:16:09+00:00\",\"dateModified\":\"2026-05-05T10:28:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/opera-2026-napoli-milionaria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/opera-2026-napoli-milionaria\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/opera-2026-napoli-milionaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tcbo.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\",\"item\":\"https:\\\/\\\/www.tcbo.it\\\/eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Opera 2026 | Naples Millionaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#website\",\"url\":\"https:\\\/\\\/www.tcbo.it\\\/\",\"name\":\"tcbo.it\",\"description\":\"Teatro d&#039;Opera, Musica Lirica e Sinfonica, spettacoli di Danza classica e contemporanea\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tcbo.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#organization\",\"name\":\"Fondazione Teatro Comunale di Bologna\",\"url\":\"https:\\\/\\\/www.tcbo.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tcbo.it\\\/wp-content\\\/uploads\\\/Copia-di-TCBO_-logo2016.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tcbo.it\\\/wp-content\\\/uploads\\\/Copia-di-TCBO_-logo2016.jpg\",\"width\":3325,\"height\":3325,\"caption\":\"Fondazione Teatro Comunale di Bologna\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tcbo.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TeatroComunaleBologna\",\"https:\\\/\\\/x.com\\\/ComunaleBologna\",\"https:\\\/\\\/www.instagram.com\\\/comunalebologna\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fondazione-teatro-comunale-di-bologna\\\/mycompany\\\/?viewAsMember=true\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC2YPqJpxc4Hof43oHcdCvvw\",\"https:\\\/\\\/www.tiktok.com\\\/@ilcomunalebologna\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Opera 2026 | Naples Millionaires - Teatro Comunale di Bologna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/","og_locale":"en_US","og_type":"article","og_title":"Opera 2026 | Naples Millionaires","og_description":"[vc_row][vc_column width=&#8221;4\/6&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;149354&#8243;] Let&#8217;s talk about Opera | Opera Season 2025 LET&#8217;S TALK ABOUT &#8220;A MASQUERADE BALL&#8221; WITH LODO GUENZI [\/vc_custom_heading][vc_row_inner row_inner_height_percent=&#8221;0&#8243; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; desktop_visibility=&#8221;yes&#8221; medium_visibility=&#8221;yes&#8221; limit_content=&#8221;&#8221; uncode_shortcode_id=&#8221;218726&#8243;][vc_column_inner column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; back_color=&#8221;color-gyho&#8221; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; &hellip;","og_url":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/","og_site_name":"Teatro Comunale di Bologna","article_publisher":"https:\/\/www.facebook.com\/TeatroComunaleBologna","article_modified_time":"2026-05-05T10:28:21+00:00","og_image":[{"url":"https:\/\/www.tcbo.it\/wp-content\/uploads\/2025\/12\/yoast_Napoli-milionaria-1024x576.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@ComunaleBologna","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/","url":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/","name":"Opera 2026 | Naples Millionaires - Teatro Comunale di Bologna","isPartOf":{"@id":"https:\/\/www.tcbo.it\/#website"},"datePublished":"2025-11-20T13:16:09+00:00","dateModified":"2026-05-05T10:28:21+00:00","breadcrumb":{"@id":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tcbo.it\/eventi\/opera-2026-napoli-milionaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tcbo.it\/en\/"},{"@type":"ListItem","position":2,"name":"Eventi","item":"https:\/\/www.tcbo.it\/eventi\/"},{"@type":"ListItem","position":3,"name":"Opera 2026 | Naples Millionaires"}]},{"@type":"WebSite","@id":"https:\/\/www.tcbo.it\/#website","url":"https:\/\/www.tcbo.it\/","name":"tcbo.it","description":"Teatro d&#039;Opera, Musica Lirica e Sinfonica, spettacoli di Danza classica e contemporanea","publisher":{"@id":"https:\/\/www.tcbo.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tcbo.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tcbo.it\/#organization","name":"Fondazione Teatro Comunale di Bologna","url":"https:\/\/www.tcbo.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tcbo.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.tcbo.it\/wp-content\/uploads\/Copia-di-TCBO_-logo2016.jpg","contentUrl":"https:\/\/www.tcbo.it\/wp-content\/uploads\/Copia-di-TCBO_-logo2016.jpg","width":3325,"height":3325,"caption":"Fondazione Teatro Comunale di Bologna"},"image":{"@id":"https:\/\/www.tcbo.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TeatroComunaleBologna","https:\/\/x.com\/ComunaleBologna","https:\/\/www.instagram.com\/comunalebologna\/","https:\/\/www.linkedin.com\/company\/fondazione-teatro-comunale-di-bologna\/mycompany\/?viewAsMember=true","https:\/\/www.youtube.com\/channel\/UC2YPqJpxc4Hof43oHcdCvvw","https:\/\/www.tiktok.com\/@ilcomunalebologna"]}]}},"_links":{"self":[{"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/portfolio\/120071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/comments?post=120071"}],"version-history":[{"count":14,"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/portfolio\/120071\/revisions"}],"predecessor-version":[{"id":121632,"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/portfolio\/120071\/revisions\/121632"}],"wp:attachment":[{"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/media?parent=120071"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/www.tcbo.it\/en\/wp-json\/wp\/v2\/portfolio_category?post=120071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}